{"id":39908,"date":"2025-05-27T15:44:20","date_gmt":"2025-05-27T15:44:20","guid":{"rendered":"https:\/\/buy.williamscookstools.com\/?post_type=product&#038;p=39908"},"modified":"2026-04-28T03:04:31","modified_gmt":"2026-04-29T09:41:31","slug":"louis-vuitton-z1579e-lv-clash-square-sunglasses","status":"publish","type":"product","link":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/","title":{"rendered":"Louis Vuitton Z1579E LV Clash Square Sunglasses"},"content":{"rendered":"<p class=\"lv-product__description body-s\">The LV Clash Square Sunglasses are a bold addition to the Spring-Summer 2022 Eyewear Collection for men. The new style features a modern shape and an oversized frame for a confident look. This accessory pays homage to the House with distinctive LV Initials on each temple.<\/p>\n<div class=\"lv-product-detailed-features lv-product__detailed-features\">\n<div>\n<div class=\"lv-product-detailed-features__description body-s\">\n<ul>\n<li>Black frame<\/li>\n<li>Black lenses<\/li>\n<li>Square shape<\/li>\n<li>Gold-color hardware<\/li>\n<li>LV Initials on temples<\/li>\n<li>Louis Vuitton signature on lenses<\/li>\n<li>Transmittance:12%<\/li>\n<li>UV Protection:100%<\/li>\n<li>Filter Category:3<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>The LV Clash Square Sunglasses are a bold addition to the Spring-Summer 2022 Eyewear Collection for men. The new style<\/p>\n","protected":false},"featured_media":39909,"template":"","meta":[],"product_brand":[],"product_cat":[349,397,628],"product_tag":[],"class_list":{"0":"post-39908","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-best-sellers","7":"product_cat-new-arrivals","8":"product_cat-sunglasses","9":"pa_material-gold-color-hardware","11":"first","12":"instock","13":"sale","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.5 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses On Sale - Bags Outlet \u00ae<\/title>\n<meta name=\"description\" content=\"Get one of the hottest styles of the season! The Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses is a top 10 member favorite on Outlet Louis Vuitton Online Store. Save on yours before they&#039;re sold out!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses On Sale - Bags Outlet \u00ae\" \/>\n<meta property=\"og:description\" content=\"Get one of the hottest styles of the season! The Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses is a top 10 member favorite on Outlet Louis Vuitton Online Store. Save on yours before they&#039;re sold out!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/\" \/>\n<meta property=\"og:site_name\" content=\"Bags Outlet \u00ae\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T09:41:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/\",\"url\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/\",\"name\":\"Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses On Sale - Bags Outlet \u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg\",\"datePublished\":\"2025-05-27T15:44:20+00:00\",\"dateModified\":\"2026-04-29T09:41:31+00:00\",\"description\":\"Get one of the hottest styles of the season! The Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses is a top 10 member favorite on Outlet Louis Vuitton Online Store. Save on yours before they're sold out!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#primaryimage\",\"url\":\"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg\",\"contentUrl\":\"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg\",\"width\":1440,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.outletbags.us.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Louis Vuitton Outlet Sale\",\"item\":\"https:\/\/www.outletbags.us.com\/home\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Louis Vuitton Z1579E LV Clash Square Sunglasses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.outletbags.us.com\/home\/#website\",\"url\":\"https:\/\/www.outletbags.us.com\/home\/\",\"name\":\"Louis Vuitton Outlet \u00ae\",\"description\":\"Bags Outlet \u00ae\",\"publisher\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/#organization\"},\"alternateName\":\"Lv Outlet\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.outletbags.us.com\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Organization\",\"Place\",\"ShoppingCenter\"],\"@id\":\"https:\/\/www.outletbags.us.com\/home\/#organization\",\"name\":\"Louis Vuitton Outlet\",\"alternateName\":\"Lv Outlet\",\"url\":\"https:\/\/www.outletbags.us.com\/home\/\",\"logo\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-organization-logo\"},\"publishingPrinciples\":\"https:\/\/www.outletbags.us.com\/home\/faq\/\",\"ownershipFundingInfo\":\"https:\/\/www.outletbags.us.com\/home\/contact-us\/\",\"address\":{\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-place-address\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"20:00\"}],\"email\":\"servicebags711@gmail.com\",\"areaServed\":\"US,CA,EU,AU\",\"priceRange\":\"$\",\"paymentAccepted\":\"Paypal\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-place-address\",\"streetAddress\":\"1949 W Corporate Way #11282\",\"addressLocality\":\"Anaheim\",\"postalCode\":\"92801\",\"addressRegion\":\"California\",\"addressCountry\":\"US\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-organization-logo\",\"url\":\"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/12\/louis_vuitton_outlet.png\",\"contentUrl\":\"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/12\/louis_vuitton_outlet.png\",\"width\":2516,\"height\":956,\"caption\":\"Louis Vuitton Outlet\"}]}<\/script>\n<meta property=\"product:brand\" content=\"Louis Vuitton\" \/>\n<meta property=\"product:price:amount\" content=\"75.00\" \/>\n<meta property=\"product:price:currency\" content=\"USD\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"Z1579E\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<meta name=\"geo.placename\" content=\"Anaheim\" \/>\n<meta name=\"geo.region\" content=\"United States (US)\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses On Sale - Bags Outlet \u00ae","description":"Get one of the hottest styles of the season! The Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses is a top 10 member favorite on Outlet Louis Vuitton Online Store. Save on yours before they're sold out!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/","og_locale":"en_US","og_type":"article","og_title":"Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses On Sale - Bags Outlet \u00ae","og_description":"Get one of the hottest styles of the season! The Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses is a top 10 member favorite on Outlet Louis Vuitton Online Store. Save on yours before they're sold out!","og_url":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/","og_site_name":"Bags Outlet \u00ae","article_modified_time":"2026-04-29T09:41:31+00:00","og_image":[{"width":1440,"height":1440,"url":"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/","url":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/","name":"Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses On Sale - Bags Outlet \u00ae","isPartOf":{"@id":"https:\/\/www.outletbags.us.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#primaryimage"},"image":{"@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#primaryimage"},"thumbnailUrl":"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg","datePublished":"2025-05-27T15:44:20+00:00","dateModified":"2026-04-29T09:41:31+00:00","description":"Get one of the hottest styles of the season! The Outlet Louis Vuitton Z1579E LV Clash Square Sunglasses is a top 10 member favorite on Outlet Louis Vuitton Online Store. Save on yours before they're sold out!","breadcrumb":{"@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#primaryimage","url":"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg","contentUrl":"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/05\/louis-vuitton-lv-clash-square-sunglasses-Z1579E_PM1_Back-view.jpg","width":1440,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.outletbags.us.com\/home\/"},{"@type":"ListItem","position":2,"name":"Louis Vuitton Outlet Sale","item":"https:\/\/www.outletbags.us.com\/home\/shop\/"},{"@type":"ListItem","position":3,"name":"Louis Vuitton Z1579E LV Clash Square Sunglasses"}]},{"@type":"WebSite","@id":"https:\/\/www.outletbags.us.com\/home\/#website","url":"https:\/\/www.outletbags.us.com\/home\/","name":"Louis Vuitton Outlet \u00ae","description":"Bags Outlet \u00ae","publisher":{"@id":"https:\/\/www.outletbags.us.com\/home\/#organization"},"alternateName":"Lv Outlet","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.outletbags.us.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Organization","Place","ShoppingCenter"],"@id":"https:\/\/www.outletbags.us.com\/home\/#organization","name":"Louis Vuitton Outlet","alternateName":"Lv Outlet","url":"https:\/\/www.outletbags.us.com\/home\/","logo":{"@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-organization-logo"},"publishingPrinciples":"https:\/\/www.outletbags.us.com\/home\/faq\/","ownershipFundingInfo":"https:\/\/www.outletbags.us.com\/home\/contact-us\/","address":{"@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-place-address"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"20:00"}],"email":"servicebags711@gmail.com","areaServed":"US,CA,EU,AU","priceRange":"$","paymentAccepted":"Paypal"},{"@type":"PostalAddress","@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-place-address","streetAddress":"1949 W Corporate Way #11282","addressLocality":"Anaheim","postalCode":"92801","addressRegion":"California","addressCountry":"US"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.outletbags.us.com\/home\/product\/louis-vuitton-z1579e-lv-clash-square-sunglasses\/#local-main-organization-logo","url":"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/12\/louis_vuitton_outlet.png","contentUrl":"https:\/\/www.outletbags.us.com\/wp-content\/uploads\/2025\/12\/louis_vuitton_outlet.png","width":2516,"height":956,"caption":"Louis Vuitton Outlet"}]},"product_brand":"Louis Vuitton","product_price_amount":"75.00","product_price_currency":"USD","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"Z1579E","product_condition":"new","geo.placename":"Anaheim","geo.region":"United States (US)"},"_links":{"self":[{"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/product\/39908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/product\/39908\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/media\/39909"}],"wp:attachment":[{"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/media?parent=39908"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/product_brand?post=39908"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/product_cat?post=39908"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.outletbags.us.com\/home\/wp-json\/wp\/v2\/product_tag?post=39908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}